{"id":3621,"date":"2020-08-19T16:54:46","date_gmt":"2020-08-19T16:54:46","guid":{"rendered":"https:\/\/www.dsengineers.com\/bio-based-industries\/"},"modified":"2022-09-27T14:03:23","modified_gmt":"2022-09-27T14:03:23","slug":"industries-biosourcees","status":"publish","type":"page","link":"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/","title":{"rendered":"Industries Biosourc\u00e9es"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row el_class=\u00a0\u00bbbox-shadow mb-5&Prime;][vc_column el_class=\u00a0\u00bbbg-white above ht-14 pt-2 pl-3 pr-3&Prime;][vc_row_inner][vc_column_inner width=\u00a0\u00bb1\/2&Prime;][vc_single_image image=\u00a0\u00bb16126&Prime; img_size=\u00a0\u00bb600&#215;600&Prime; alignment=\u00a0\u00bbcenter\u00a0\u00bb el_class=\u00a0\u00bbbox-shadow\u00a0\u00bb][\/vc_column_inner][vc_column_inner el_class=\u00a0\u00bbp-0 p-md-1&Prime; width=\u00a0\u00bb1\/2&Prime;][vc_empty_space height=\u00a0\u00bb22px\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbChimie verte &amp; bioraffineries\u00a0\u00bb font_container=\u00a0\u00bbtag:h1|text_align:left|color:%23027983&Prime; use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_empty_space][vc_column_text]D&rsquo;un point de vue technique, la plupart des mat\u00e9riaux industriels fabriqu\u00e9s \u00e0 partir de ressources fossiles, en tout cas respectivement leurs composants des base, peuvent \u00eatre remplac\u00e9s par leurs \u00e9quivalents bio-sourc\u00e9s.<\/p>\n<p>Gr\u00e2ce \u00e0 son expertise dans les op\u00e9rations unitaires en sucrerie et en huilerie, <strong>De Smet Engineers &amp; Contractors (DSEC)<\/strong> est le partenaire id\u00e9al pour accompagner les investisseurs et les start-up dans le d\u00e9veloppement et la mise en \u0153uvre de <strong>proc\u00e9d\u00e9s bio-industriels<\/strong> et de <strong>bioraffineries<\/strong>.<\/p>\n<p>Notre compr\u00e9hension des exigences des fournisseurs de technologie quant aux proc\u00e9d\u00e9s aval, combin\u00e9e \u00e0 notre vaste exp\u00e9rience dans l&rsquo;agro-industrie, nous permet d&rsquo;\u00e9valuer et de valider toutes les \u00e9tapes du d\u00e9veloppement des proc\u00e9d\u00e9s et de la d\u00e9finition des produits afin d&rsquo;atteindre un concept complet et une mise \u00e0 l&rsquo;\u00e9chelle avant le d\u00e9marrage effectif du projet (Pilote \u00e0 D\u00e9mo \u00e0 Industriel).[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb el_class=\u00a0\u00bbpt-3 pb-4 bg-right-bottom\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1595855247783{background: #027983 url(https:\/\/www.dsengineers.com\/files\/uploads\/2020\/07\/vegetable-oil-opacity.svg?id=802) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;}\u00a0\u00bb][vc_column][vc_row_inner equal_height=\u00a0\u00bbyes\u00a0\u00bb content_placement=\u00a0\u00bbmiddle\u00a0\u00bb gap=\u00a0\u00bb15&Prime;][vc_column_inner el_class=\u00a0\u00bbbg-white box-shadow\u00a0\u00bb width=\u00a0\u00bb1\/4&Prime;][vc_single_image image=\u00a0\u00bb15461&Prime; img_size=\u00a0\u00bb\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb css_animation=\u00a0\u00bbappear\u00a0\u00bb el_class=\u00a0\u00bbsvg-sugar pt-2 pt-md-0&Prime;][vc_custom_heading text=\u00a0\u00bbIndustries<br \/>\nBiosourcees\u00a0\u00bb font_container=\u00a0\u00bbtag:h4|font_size:27|text_align:center|color:%23027983&Prime; use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css_animation=\u00a0\u00bbappear\u00a0\u00bb el_class=\u00a0\u00bbpb-2 pb-md-0&Prime;][\/vc_column_inner][vc_column_inner el_class=\u00a0\u00bbp-2 p-md-4 bg-white box-shadow\u00a0\u00bb width=\u00a0\u00bb3\/4&Prime;][vc_custom_heading text=\u00a0\u00bbProduits bio-bas\u00e9s\u00a0\u00bb font_container=\u00a0\u00bbtag:h4|text_align:left|color:%23027983&Prime; use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb][vc_column_text el_class=\u00a0\u00bbmb-0&Prime;]Ce secteur en plein essor a besoin de toute la flexibilit\u00e9 et de l&rsquo;expertise d&rsquo;entreprises comme DSEC pour mettre en \u0153uvre des proc\u00e9d\u00e9s issus \u00e0 la fois du g\u00e9nie chimique et des biotechnologies, tels que :<\/p>\n<ul>\n<li>Fermentation<\/li>\n<li>Technologies de s\u00e9paration<\/li>\n<li>Technologies membranaires<\/li>\n<li>Technologies de purification et de concentration<\/li>\n<\/ul>\n<p>DSEC se diff\u00e9rencie \u00e9galement de ses concurrents gr\u00e2ce \u00e0 sa connaissance de la manutention et de la pr\u00e9paration des mati\u00e8res premi\u00e8res, \u00e9tape cl\u00e9 avant les proc\u00e9d\u00e9s aval (Down Stream Process).<\/p>\n<p>La longue exp\u00e9rience de DSEC s&rsquo;est d\u00e9velopp\u00e9e avec succ\u00e8s au profit des secteurs de l\u2019<strong>Oligofructose<\/strong> et de la <strong>Bio-chimie<\/strong> o\u00f9 ces comp\u00e9tences s\u2019\u00e9tendent du traitement des mati\u00e8res premi\u00e8res au conditionnement des produits finis.<\/p>\n<p>La <strong>biomasse cellulosique<\/strong> qui est la partie structurelle des plantes constitue une mati\u00e8re premi\u00e8re durable par excellence. Elle comprend les r\u00e9sidus agricoles, les r\u00e9sidus forestiers, les principales fractions de d\u00e9chets solides municipaux, les cultures herbac\u00e9es et les cultures ligneuses cultiv\u00e9es en tant que ressources \u00e9nerg\u00e9tiques.<\/p>\n<p>Les services d\u2019ing\u00e9nierie et de gestion de DSEC offrent aux investisseurs une grande vari\u00e9t\u00e9 de <a href=\"\/fr\/services-et-execution\/\"><strong>configurations contractuelles<\/strong><\/a> allant de l&rsquo;ing\u00e9nierie conceptuelle et <a href=\"\/fr\/services-et-execution\/audits-etudes-dingenierie-fel1-2-3-feed\/\"><strong>\u00e9tudes d\u2019avant-projet<\/strong> (<strong>APS<\/strong> \/ <strong>APD<\/strong> \/ <strong>FEED<\/strong>)<\/a> aux <a href=\"\/fr\/services-et-execution\/construction-cle-en-main-epc-complet-ou-partiel\/\"><strong>projets cl\u00e9 en main complet<\/strong> (<strong>EPC<\/strong>)<\/a> ou aux mandats de Maitrise d\u2019\u0152uvre (<a href=\"\/fr\/services-et-execution\/gestion-complete-de-projet-maitrise-doeuvre-epcm\/\"><strong>EPCM<\/strong><\/a>) afin de s&rsquo;adapter aux exigences de chaque situation.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row_content_no_spaces\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1595855320436{background-color: #027983 !important;}\u00a0\u00bb el_class=\u00a0\u00bbpt-2 pb-5&Prime;][vc_column][vc_separator color=\u00a0\u00bbcustom\u00a0\u00bb el_width=\u00a0\u00bb90&Prime; css_animation=\u00a0\u00bbslideInUp\u00a0\u00bb accent_color=\u00a0\u00bb#b2d7da\u00a0\u00bb][vc_custom_heading text=\u00a0\u00bbDSEC EST ACTIF DANS LES INDUSTRIES DE PRODUCTION LI\u00c9ES AUX PRODUITS BIO-BAS\u00c9S\u00a0\u00bb font_container=\u00a0\u00bbtag:h2|text_align:center|color:%23ffffff\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css_animation=\u00a0\u00bbslideInUp\u00a0\u00bb el_class=\u00a0\u00bbpb-2&Prime;]<div class=\"templatera_shortcode\"><script data-type=\"vc_custom-js-header\"><\/script><script data-type=\"vc_custom-js-footer\"><\/script><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"mpc-carousel__wrapper mpc-waypoint\"><div id=\"mpc_carousel_posts-76a97b2ea5e603\" class=\"mpc-carousel-posts mpc-init mpc-init mpc-transition mpc-overlay--fade mpc-item--fade mpc-layout--style_2 carousel-services-activities pl-0 pl-xl-1 pr-0 pr-xl-1 carousel-services-activities pl-0 pl-xl-1 pr-0 pr-xl-1\"   data-mpcslick='{\"infinite\":true,\"autoplay\":true,\"slidesToShow\":4,\"slidesToScroll\":4,\"centerMode\":false,\"initialSlide\":0,\"autoplaySpeed\":3000}' data-slick-cols=\"4\"><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/www.dsengineers.com\/files\/uploads\/2021\/10\/20210923_105206-Crpd2-1024x452.jpg\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/unites-de-production-biochimique\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/unites-de-production-biochimique\/\"><a href=\"https:\/\/www.dsengineers.com\/files\/uploads\/2021\/10\/20210923_105206-Crpd2.jpg\" title=\"Chimie bio-sourc\u00e9e\" class=\"mpc-lightbox mpc-icon-anchor mpc-pretty-photo\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox lnr lnr-link\"><\/i><\/a><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition\"><a href=\"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/unites-de-production-biochimique\/\" title=\"Chimie bio-sourc\u00e9e\">Chimie bio-sourc\u00e9e<\/a><\/h3><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/Biomass-CRISTABA-2012-04-Biomass-boiler-island--1024x736.jpg\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/cogeneration-biomasse-epc\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/cogeneration-biomasse-epc\/\"><a href=\"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/Biomass-CRISTABA-2012-04-Biomass-boiler-island-.jpg\" title=\"Biomasse pour production d&rsquo;\u00e9nergie et cog\u00e9n\u00e9ration\" class=\"mpc-lightbox mpc-icon-anchor mpc-pretty-photo\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox lnr lnr-link\"><\/i><\/a><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition\"><a href=\"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/cogeneration-biomasse-epc\/\" title=\"Biomasse pour production d&rsquo;\u00e9nergie et cog\u00e9n\u00e9ration\">Biomasse pour production d&rsquo;\u00e9nergie et cog\u00e9n\u00e9ration<\/a><\/h3><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/www.dsengineers.com\/files\/uploads\/2022\/09\/Fibenol-Lignin-Wood-Sugars-crpd-1024x528.jpg\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/matieres-premieres-cellulosiques-pour-ethanol\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/matieres-premieres-cellulosiques-pour-ethanol\/\"><a href=\"https:\/\/www.dsengineers.com\/files\/uploads\/2022\/09\/Fibenol-Lignin-Wood-Sugars-crpd.jpg\" title=\"Ethanol de 2\u00e8me g\u00e9n\u00e9ration, lignine et d\u00e9riv\u00e9s de cellulose\" class=\"mpc-lightbox mpc-icon-anchor mpc-pretty-photo\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox lnr lnr-link\"><\/i><\/a><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition\"><a href=\"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/matieres-premieres-cellulosiques-pour-ethanol\/\" title=\"Ethanol de 2\u00e8me g\u00e9n\u00e9ration, lignine et d\u00e9riv\u00e9s de cellulose\">Ethanol de 2\u00e8me g\u00e9n\u00e9ration, lignine et d\u00e9riv\u00e9s de cellulose<\/a><\/h3><\/div><\/div><\/div><\/div><div class=\"mpc-navigation mpc-init mpc-align--right mpc-navigation--style_1  mpc-nav-preset--preset_0\" data-mpcslider=\"mpc_carousel_posts-76a97b2ea5e603\"><div class=\"mpc-nav__arrow mpcslick-prev\"><div class=\"mpc-nav__icon mpc-transition\"><i class=\" eti eti_arrow_left\"><div class=\"mpc-nav__background mpc-transition mpc-effect-type--slide mpc-effect-side--top\"><\/div><\/i><\/div><\/div><div class=\"mpc-nav__arrow mpcslick-next\"><div class=\"mpc-nav__icon mpc-transition\"><i class=\" eti eti_arrow_right\"><div class=\"mpc-nav__background mpc-transition mpc-effect-type--slide mpc-effect-side--top\"><\/div><\/i><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row_content_no_spaces\u00a0\u00bb el_class=\u00a0\u00bbpt-3&Prime;][vc_column][vc_custom_heading text=\u00a0\u00bbPROJETS MAJEURS &#8211; Industries Biosourcees\u00a0\u00bb font_container=\u00a0\u00bbtag:h2|text_align:center\u00a0\u00bb use_theme_fonts=\u00a0\u00bbyes\u00a0\u00bb css_animation=\u00a0\u00bbslideInUp\u00a0\u00bb el_class=\u00a0\u00bbpb-2&Prime;][\/vc_column][\/vc_row][vc_row el_class=\u00a0\u00bbpb-2&Prime;][vc_column]<div class=\"templatera_shortcode\"><script data-type=\"vc_custom-js-header\"><\/script><script data-type=\"vc_custom-js-footer\"><\/script><div class=\"vc_row wpb_row vc_row-fluid pb-2\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"mpc-carousel__wrapper mpc-waypoint\"><div id=\"mpc_carousel_posts-326a97b2ea609f4\" class=\"mpc-carousel-posts mpc-init mpc-init mpc-transition mpc-overlay--fade mpc-item--fade mpc-layout--style_2 carousel-keys pl-0 pl-xl-6 pr-0 pr-xl-6 carousel-keys pl-0 pl-xl-6 pr-0 pr-xl-6\"   data-mpcslick='{\"infinite\":true,\"autoplay\":true,\"slidesToShow\":4,\"slidesToScroll\":4,\"centerMode\":false,\"initialSlide\":0,\"autoplaySpeed\":3000}' data-slick-cols=\"4\"><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/Polysaccharide-Pectin-Plant-DSEC-1-1024x576.jpg\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/references\/cargill-pectin-production-plant-in-france\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/references\/cargill-pectin-production-plant-in-france\/\"><a href=\"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/Polysaccharide-Pectin-Plant-DSEC-1.jpg\" title=\"CARGILL Pectin Production Plant in France\" class=\"mpc-lightbox mpc-icon-anchor mpc-pretty-photo\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox lnr lnr-link\"><\/i><\/a><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition\"><a href=\"https:\/\/www.dsengineers.com\/fr\/references\/cargill-pectin-production-plant-in-france\/\" title=\"CARGILL Pectin Production Plant in France\">CARGILL Pectin Production Plant in France<\/a><\/h3><a href=\"https:\/\/www.dsengineers.com\/fr\/references\/cargill-pectin-production-plant-in-france\/\" title=\"CARGILL Pectin Production Plant in France\"  class=\"mpc-button mpc-init mpc-transition mpc-display--block \" ><div class=\"mpc-button__content mpc-effect-type--stay mpc-effect-side--right\"><span class=\"mpc-button__title mpc-transition\">EN SAVOIR PLUS<\/span><i class=\"mpc-button__icon mpc-transition  lnr lnr-arrow-right\"><\/i><\/div><div class=\"mpc-button__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/a><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\">in <a href=\"https:\/\/www.dsengineers.com\/fr\/category\/engineering-management-works-epcm-fr\/\" rel=\"category tag\">EPCM (Gestion Cl\u00e9 en main)<\/a><\/span><\/div><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/DJI_0010-Crpd-1024x576.jpg\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/references\/europeenne-de-biomasse-white-black-pellets-reversible-biomass-plant-france\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/references\/europeenne-de-biomasse-white-black-pellets-reversible-biomass-plant-france\/\"><a href=\"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/DJI_0010-Crpd.jpg\" title=\"EUROPEENNE DE BIOMASSE White &#038; Black Pellets reversible Biomass plant, France\" class=\"mpc-lightbox mpc-icon-anchor mpc-pretty-photo\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox lnr lnr-link\"><\/i><\/a><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition\"><a href=\"https:\/\/www.dsengineers.com\/fr\/references\/europeenne-de-biomasse-white-black-pellets-reversible-biomass-plant-france\/\" title=\"EUROPEENNE DE BIOMASSE White &#038; Black Pellets reversible Biomass plant, France\">EUROPEENNE DE BIOMASSE White &#038; Black Pellets reversible Biomass plant, France<\/a><\/h3><a href=\"https:\/\/www.dsengineers.com\/fr\/references\/europeenne-de-biomasse-white-black-pellets-reversible-biomass-plant-france\/\" title=\"EUROPEENNE DE BIOMASSE White &#038; Black Pellets reversible Biomass plant, France\"  class=\"mpc-button mpc-init mpc-transition mpc-display--block \" ><div class=\"mpc-button__content mpc-effect-type--stay mpc-effect-side--right\"><span class=\"mpc-button__title mpc-transition\">EN SAVOIR PLUS<\/span><i class=\"mpc-button__icon mpc-transition  lnr lnr-arrow-right\"><\/i><\/div><div class=\"mpc-button__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/a><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\">in <a href=\"https:\/\/www.dsengineers.com\/fr\/category\/complete-projects-epc-fr\/\" rel=\"category tag\">EPC (Construction Cl\u00e9 en main)<\/a><\/span><\/div><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/20210923_105344-1024x575.jpg\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/references\/metex-noovista-propanediol-butyric-acid-production-plant-france\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/references\/metex-noovista-propanediol-butyric-acid-production-plant-france\/\"><a href=\"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/20210923_105344.jpg\" title=\"METEX N\u00d8\u00d8VISTA Propanediol &#038; Butyric Acid production plant, France\" class=\"mpc-lightbox mpc-icon-anchor mpc-pretty-photo\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox lnr lnr-link\"><\/i><\/a><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition\"><a href=\"https:\/\/www.dsengineers.com\/fr\/references\/metex-noovista-propanediol-butyric-acid-production-plant-france\/\" title=\"METEX N\u00d8\u00d8VISTA Propanediol &#038; Butyric Acid production plant, France\">METEX N\u00d8\u00d8VISTA Propanediol &#038; Butyric Acid production plant, France<\/a><\/h3><a href=\"https:\/\/www.dsengineers.com\/fr\/references\/metex-noovista-propanediol-butyric-acid-production-plant-france\/\" title=\"METEX N\u00d8\u00d8VISTA Propanediol &#038; Butyric Acid production plant, France\"  class=\"mpc-button mpc-init mpc-transition mpc-display--block \" ><div class=\"mpc-button__content mpc-effect-type--stay mpc-effect-side--right\"><span class=\"mpc-button__title mpc-transition\">EN SAVOIR PLUS<\/span><i class=\"mpc-button__icon mpc-transition  lnr lnr-arrow-right\"><\/i><\/div><div class=\"mpc-button__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/a><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\">in <a href=\"https:\/\/www.dsengineers.com\/fr\/category\/engineering-management-works-epcm-fr\/\" rel=\"category tag\">EPCM (Gestion Cl\u00e9 en main)<\/a><\/span><\/div><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/www.dsengineers.com\/files\/uploads\/2022\/01\/GBBIO-1600-Fibenol-Crpd-1-1024x768.jpg\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/references\/fibenol-flagship-lignin-plant-estonia\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/references\/fibenol-flagship-lignin-plant-estonia\/\"><a href=\"https:\/\/www.dsengineers.com\/files\/uploads\/2022\/01\/GBBIO-1600-Fibenol-Crpd-1.jpg\" title=\"FIBENOL Flagship Lignin Plant, Estonia\" class=\"mpc-lightbox mpc-icon-anchor mpc-pretty-photo\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox lnr lnr-link\"><\/i><\/a><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition\"><a href=\"https:\/\/www.dsengineers.com\/fr\/references\/fibenol-flagship-lignin-plant-estonia\/\" title=\"FIBENOL Flagship Lignin Plant, Estonia\">FIBENOL Flagship Lignin Plant, Estonia<\/a><\/h3><a href=\"https:\/\/www.dsengineers.com\/fr\/references\/fibenol-flagship-lignin-plant-estonia\/\" title=\"FIBENOL Flagship Lignin Plant, Estonia\"  class=\"mpc-button mpc-init mpc-transition mpc-display--block \" ><div class=\"mpc-button__content mpc-effect-type--stay mpc-effect-side--right\"><span class=\"mpc-button__title mpc-transition\">EN SAVOIR PLUS<\/span><i class=\"mpc-button__icon mpc-transition  lnr lnr-arrow-right\"><\/i><\/div><div class=\"mpc-button__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/a><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\">in <a href=\"https:\/\/www.dsengineers.com\/fr\/category\/engineering-management-works-epcm-fr\/\" rel=\"category tag\">EPCM (Gestion Cl\u00e9 en main)<\/a><\/span><\/div><\/div><\/div><\/div><div onclick=\"\" class=\"mpc-post\"><div class=\"mpc-post__wrapper\"><div class=\"mpc-post__thumbnail\" data-mpc_src=\"https:\/\/www.dsengineers.com\/files\/uploads\/2022\/10\/ReSolute-Project-CIRCA-ST-AVOLD-1024x576.jpg\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/references\/circa-resolute-bio-based-plant-france\/\"><div class=\"mpc-post__overlay mpc-transition\"><div class=\"mpc-post--vertical-wrap\"><div class=\"mpc-post--vertical\" data-mpc_link=\"https:\/\/www.dsengineers.com\/fr\/references\/circa-resolute-bio-based-plant-france\/\"><a href=\"https:\/\/www.dsengineers.com\/files\/uploads\/2022\/10\/ReSolute-Project-CIRCA-ST-AVOLD.jpg\" title=\"CIRCA RESOLUTE Bio-Based Solvent Plant, France &#8211; On Hold\" class=\"mpc-lightbox mpc-icon-anchor mpc-pretty-photo\"><i class=\"mpc-post-overlay__icon mpc-type--lightbox lnr lnr-link\"><\/i><\/a><\/div><\/div><\/div><\/div><div class=\"mpc-post__content mpc-transition\"><h3 class=\"mpc-post__heading mpc-transition\"><a href=\"https:\/\/www.dsengineers.com\/fr\/references\/circa-resolute-bio-based-plant-france\/\" title=\"CIRCA RESOLUTE Bio-Based Solvent Plant, France &#8211; On Hold\">CIRCA RESOLUTE Bio-Based Solvent Plant, France &#8211; On Hold<\/a><\/h3><a href=\"https:\/\/www.dsengineers.com\/fr\/references\/circa-resolute-bio-based-plant-france\/\" title=\"CIRCA RESOLUTE Bio-Based Solvent Plant, France &#8211; On Hold\"  class=\"mpc-button mpc-init mpc-transition mpc-display--block \" ><div class=\"mpc-button__content mpc-effect-type--stay mpc-effect-side--right\"><span class=\"mpc-button__title mpc-transition\">EN SAVOIR PLUS<\/span><i class=\"mpc-button__icon mpc-transition  lnr lnr-arrow-right\"><\/i><\/div><div class=\"mpc-button__background mpc-transition mpc-effect-type--fade mpc-effect-side--in\"><\/div><\/a><div class=\"mpc-post__meta mpc-transition\"><span class=\"mpc-post__tax\">in <a href=\"https:\/\/www.dsengineers.com\/fr\/category\/engineering-management-works-epcm-fr\/\" rel=\"category tag\">EPCM (Gestion Cl\u00e9 en main)<\/a>, <a href=\"https:\/\/www.dsengineers.com\/fr\/category\/work-in-progress-fr\/\" rel=\"category tag\">Travaux en cours<\/a><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-navigation mpc-init mpc-align--right mpc-navigation--style_1  mpc-nav-preset--mpc_preset_2\" data-mpcslider=\"mpc_carousel_posts-326a97b2ea609f4\"><div class=\"mpc-nav__arrow mpcslick-prev\"><div class=\"mpc-nav__icon mpc-transition\"><i class=\" eti eti_arrow_left\"><div class=\"mpc-nav__background mpc-transition mpc-effect-type--slide mpc-effect-side--top\"><\/div><\/i><\/div><\/div><div class=\"mpc-nav__arrow mpcslick-next\"><div class=\"mpc-nav__icon mpc-transition\"><i class=\" eti eti_arrow_right\"><div class=\"mpc-nav__background mpc-transition mpc-effect-type--slide mpc-effect-side--top\"><\/div><\/i><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"On Hold Construction of a high-performance Bio Solvent Production Plant from Woody Biomass DSEC Projects World Map View Customer CIRCA Sustainable Chemicals France SAS Scope of works EPCM: Project Management, Detailed Engineering, Procurement Assistance, early Site supervision Plant capacity 1,000 TPY Bio Solvent Products CYRENE\u2122 Solvent &amp; Levoglucosenone (LGO) Industrial operation 2024 Processing units Wood","protected":false},"author":4,"featured_media":3138,"parent":4322,"menu_order":20,"comment_status":"closed","ping_status":"closed","template":"header-industries.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-3621","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Industries Biosourc\u00e9es | De Smet Engineers &amp; Contractors (DSEC)<\/title>\n<meta name=\"description\" content=\"Le d\u00e9veloppement de l\u2019expertise biosourc\u00e9e de DSEC dans les secteurs oligofructose et biochimique est une garantie pour la conception et la construction de votre usine.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Industries Biosourc\u00e9es | De Smet Engineers &amp; Contractors (DSEC)\" \/>\n<meta property=\"og:description\" content=\"Le d\u00e9veloppement de l\u2019expertise biosourc\u00e9e de DSEC dans les secteurs oligofructose et biochimique est une garantie pour la conception et la construction de votre usine.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/\" \/>\n<meta property=\"og:site_name\" content=\"De Smet Engineers &amp; Contractors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DeSmetEngineers\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-27T14:03:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/bio-based-industries.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"614\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/solutions-for-industries\\\/industries-biosourcees\\\/\",\"url\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/solutions-for-industries\\\/industries-biosourcees\\\/\",\"name\":\"Industries Biosourc\u00e9es | De Smet Engineers &amp; Contractors (DSEC)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/solutions-for-industries\\\/industries-biosourcees\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/solutions-for-industries\\\/industries-biosourcees\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.dsengineers.com\\\/files\\\/uploads\\\/2020\\\/08\\\/bio-based-industries.jpg\",\"datePublished\":\"2020-08-19T16:54:46+00:00\",\"dateModified\":\"2022-09-27T14:03:23+00:00\",\"description\":\"Le d\u00e9veloppement de l\u2019expertise biosourc\u00e9e de DSEC dans les secteurs oligofructose et biochimique est une garantie pour la conception et la construction de votre usine.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/solutions-for-industries\\\/industries-biosourcees\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/solutions-for-industries\\\/industries-biosourcees\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/solutions-for-industries\\\/industries-biosourcees\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.dsengineers.com\\\/files\\\/uploads\\\/2020\\\/08\\\/bio-based-industries.jpg\",\"contentUrl\":\"https:\\\/\\\/www.dsengineers.com\\\/files\\\/uploads\\\/2020\\\/08\\\/bio-based-industries.jpg\",\"width\":1920,\"height\":614},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/solutions-for-industries\\\/industries-biosourcees\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solutions pour industries\",\"item\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/solutions-for-industries\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Industries Biosourc\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/\",\"name\":\"De Smet Engineers &amp; Contractors\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/#organization\",\"name\":\"De Smet Engineers & Contractors\",\"url\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.dsengineers.com\\\/files\\\/uploads\\\/2020\\\/08\\\/desmet-engineers-logo-web.jpg\",\"contentUrl\":\"https:\\\/\\\/www.dsengineers.com\\\/files\\\/uploads\\\/2020\\\/08\\\/desmet-engineers-logo-web.jpg\",\"width\":1615,\"height\":609,\"caption\":\"De Smet Engineers & Contractors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.dsengineers.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DeSmetEngineers\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/DeSmetEngineers\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Industries Biosourc\u00e9es | De Smet Engineers &amp; Contractors (DSEC)","description":"Le d\u00e9veloppement de l\u2019expertise biosourc\u00e9e de DSEC dans les secteurs oligofructose et biochimique est une garantie pour la conception et la construction de votre usine.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/","og_locale":"fr_FR","og_type":"article","og_title":"Industries Biosourc\u00e9es | De Smet Engineers &amp; Contractors (DSEC)","og_description":"Le d\u00e9veloppement de l\u2019expertise biosourc\u00e9e de DSEC dans les secteurs oligofructose et biochimique est une garantie pour la conception et la construction de votre usine.","og_url":"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/","og_site_name":"De Smet Engineers &amp; Contractors","article_publisher":"https:\/\/www.facebook.com\/DeSmetEngineers","article_modified_time":"2022-09-27T14:03:23+00:00","og_image":[{"width":1920,"height":614,"url":"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/bio-based-industries.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/","url":"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/","name":"Industries Biosourc\u00e9es | De Smet Engineers &amp; Contractors (DSEC)","isPartOf":{"@id":"https:\/\/www.dsengineers.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/#primaryimage"},"image":{"@id":"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/bio-based-industries.jpg","datePublished":"2020-08-19T16:54:46+00:00","dateModified":"2022-09-27T14:03:23+00:00","description":"Le d\u00e9veloppement de l\u2019expertise biosourc\u00e9e de DSEC dans les secteurs oligofructose et biochimique est une garantie pour la conception et la construction de votre usine.","breadcrumb":{"@id":"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/#primaryimage","url":"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/bio-based-industries.jpg","contentUrl":"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/bio-based-industries.jpg","width":1920,"height":614},{"@type":"BreadcrumbList","@id":"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/industries-biosourcees\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.dsengineers.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Solutions pour industries","item":"https:\/\/www.dsengineers.com\/fr\/solutions-for-industries\/"},{"@type":"ListItem","position":3,"name":"Industries Biosourc\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/www.dsengineers.com\/fr\/#website","url":"https:\/\/www.dsengineers.com\/fr\/","name":"De Smet Engineers &amp; Contractors","description":"","publisher":{"@id":"https:\/\/www.dsengineers.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dsengineers.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.dsengineers.com\/fr\/#organization","name":"De Smet Engineers & Contractors","url":"https:\/\/www.dsengineers.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.dsengineers.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/desmet-engineers-logo-web.jpg","contentUrl":"https:\/\/www.dsengineers.com\/files\/uploads\/2020\/08\/desmet-engineers-logo-web.jpg","width":1615,"height":609,"caption":"De Smet Engineers & Contractors"},"image":{"@id":"https:\/\/www.dsengineers.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DeSmetEngineers","https:\/\/www.youtube.com\/user\/DeSmetEngineers"]}]}},"_links":{"self":[{"href":"https:\/\/www.dsengineers.com\/fr\/wp-json\/wp\/v2\/pages\/3621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dsengineers.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dsengineers.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dsengineers.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dsengineers.com\/fr\/wp-json\/wp\/v2\/comments?post=3621"}],"version-history":[{"count":18,"href":"https:\/\/www.dsengineers.com\/fr\/wp-json\/wp\/v2\/pages\/3621\/revisions"}],"predecessor-version":[{"id":16954,"href":"https:\/\/www.dsengineers.com\/fr\/wp-json\/wp\/v2\/pages\/3621\/revisions\/16954"}],"up":[{"embeddable":true,"href":"https:\/\/www.dsengineers.com\/fr\/wp-json\/wp\/v2\/pages\/4322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dsengineers.com\/fr\/wp-json\/wp\/v2\/media\/3138"}],"wp:attachment":[{"href":"https:\/\/www.dsengineers.com\/fr\/wp-json\/wp\/v2\/media?parent=3621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}